{"id":2162,"date":"2022-08-01T17:18:30","date_gmt":"2022-08-01T15:18:30","guid":{"rendered":"https:\/\/www.ellenafuneralcar.com\/news-e-fiere\/"},"modified":"2023-05-03T15:23:46","modified_gmt":"2023-05-03T13:23:46","slug":"news-e-fiere","status":"publish","type":"page","link":"https:\/\/www.ellenafuneralcar.com\/en\/news-e-fiere\/","title":{"rendered":"News and exhibitions"},"content":{"rendered":"\n<section class=\"wp-block-group\">\n<div class=\"wp-block-cover is-light\" style=\"min-height:30vh;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img decoding=\"async\" width=\"1920\" height=\"757\" class=\"wp-block-cover__image-background wp-image-296\" alt=\"\" src=\"https:\/\/ellenafuneralcar.paeztr.com\/wp-content\/uploads\/2022\/06\/background-gunmetal-no-se.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2022\/06\/background-gunmetal-no-se.jpg 1920w, https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2022\/06\/background-gunmetal-no-se-300x118.jpg 300w, https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2022\/06\/background-gunmetal-no-se-1024x404.jpg 1024w, https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2022\/06\/background-gunmetal-no-se-768x303.jpg 768w, https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2022\/06\/background-gunmetal-no-se-1536x606.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><div class=\"wp-block-cover__inner-container\">\n<div class=\"wp-block-group container\">\n<div class=\"wp-block-columns row pt-5 pb-5\">\n<div class=\"wp-block-column col-12\">\n<h1 class=\"wp-block-heading text-center\">News and exhibitions<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-group background-gunmetal-dark\">\n<div class=\"wp-block-group container\">\n<div class=\"wp-block-columns row justify-content-center align-items-center pt-5\">\n<div class=\"wp-block-column col-12\">\n<main class=\"wp-block-query alignwide\"><\/main>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns row py-5\">\n<div class=\"wp-block-column col-12\">\n<main class=\"wp-block-query alignwide\"><ul class=\"is-flex-container columns-3 alignwide wp-block-post-template\"><li class=\"wp-block-post post-3784 post type-post status-publish format-standard has-post-thumbnail hentry category-fiere-en\">\n\n<div class=\"wp-block-group\"><figure style=\"margin-top:calc(1.75 * var(--wp--style--block-gap));\" class=\"alignwide wp-block-post-featured-image\"><a href=\"https:\/\/www.ellenafuneralcar.com\/en\/ellena-srl-participates-in-funeraire-2025\/\" target=\"_self\"  ><img decoding=\"async\" width=\"1400\" height=\"300\" src=\"https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2023\/12\/1400X300-FUNERAIRE2025-FR.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Ellena Srl participates in Fun\u00e9raire Paris 2025\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2023\/12\/1400X300-FUNERAIRE2025-FR.png 1400w, https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2023\/12\/1400X300-FUNERAIRE2025-FR-300x64.png 300w, https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2023\/12\/1400X300-FUNERAIRE2025-FR-1024x219.png 1024w, https:\/\/www.ellenafuneralcar.com\/wp-content\/uploads\/2023\/12\/1400X300-FUNERAIRE2025-FR-768x165.png 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/a><\/figure>\n\n<h2 style=\"font-style:normal;font-weight:300;\" class=\"alignwide wp-block-post-title has-var-wp-custom-typography-font-size-huge-clamp-2-25-rem-4-vw-2-75-rem-font-size\"><a href=\"https:\/\/www.ellenafuneralcar.com\/en\/ellena-srl-participates-in-funeraire-2025\/\" target=\"_self\" >Ellena Srl participates in Fun\u00e9raire Paris 2025<\/a><\/h2>\n\n<div style=\"font-style:italic;font-weight:400;\" class=\"wp-block-post-date has-small-font-size\"><time datetime=\"2025-11-05T16:39:22+01:00\"><a href=\"https:\/\/www.ellenafuneralcar.com\/en\/ellena-srl-participates-in-funeraire-2025\/\">November 5, 2025<\/a><\/time><\/div>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Ellena will be participating in Fun\u00e9raire Paris 2025, the funeral and cemetery trade fair in Paris Le Bourget on 19-20-21 November 2025. <\/p><\/div>\n\n<a class=\"btn btn-border mt-4 wp-block-read-more\" href=\"https:\/\/www.ellenafuneralcar.com\/en\/ellena-srl-participates-in-funeraire-2025\/\" target=\"_self\">Read more<span class=\"screen-reader-text\">: Ellena Srl participates in Fun\u00e9raire Paris 2025<\/span><\/a><\/div>\n\n<\/li><\/ul>\n\n<\/main>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2162","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/pages\/2162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/comments?post=2162"}],"version-history":[{"count":2,"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/pages\/2162\/revisions"}],"predecessor-version":[{"id":3497,"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/pages\/2162\/revisions\/3497"}],"wp:attachment":[{"href":"https:\/\/www.ellenafuneralcar.com\/en\/wp-json\/wp\/v2\/media?parent=2162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}